{"id":5032,"date":"2025-02-25T09:40:46","date_gmt":"2025-02-25T07:40:46","guid":{"rendered":"https:\/\/interim-manager-einkauf.de\/?p=5032"},"modified":"2025-02-25T10:24:31","modified_gmt":"2025-02-25T08:24:31","slug":"menschen-staerken-krisen-meistern","status":"publish","type":"post","link":"https:\/\/interim-manager-einkauf.de\/en\/menschen-staerken-krisen-meistern\/","title":{"rendered":"MENSCHEN ST\u00c4RKEN &#8211; KRISEN MEISTERN"},"content":{"rendered":"<div class=\"share-post-detail-view__update-commentary\" tabindex=\"-1\">\n<div class=\"feed-shared-inline-show-more-text        feed-shared-update-v2__description feed-shared-inline-show-more-text--minimal-padding        feed-shared-inline-show-more-text--expanded\" tabindex=\"-1\" data-artdeco-is-focused=\"true\"><\/p>\n<div class=\"update-components-text relative update-components-update-v2__commentary\" dir=\"ltr\"><span class=\"break-words          tvm-parent-container\"> <span dir=\"ltr\">Insbesondere in Krisenzeiten ist jeder Mitarbeitende im Einkauf gefordert, den wichtigsten Dreiklang des Gesamterfolges zu sichern:<\/p>\n<p>\ud83d\udcb0Profitabilit\u00e4t &#8211; Liquidit\u00e4t &#8211; Resilienz<\/p>\n<p>\u2753Frage: Kennen Sie die Kostenstrukturen und -risiken Ihrer Lieferanten und wissen Sie um die ergebniswirksamen Werthebel, mit denen Sie das Ergebnis und die Liquidit\u00e4t Ihres Unternehmens st\u00fctzen k\u00f6nnen?<\/p>\n<p>Wir bilden Sie daf\u00fcr aus! In unserem praxisnahen Training mit vielen Beispielen und \u00dcbungen erhalten Sie die Werkzeuge und das Wissen, um Kosten und Risiken zu verstehen, Einsparpotentiale zu identifizieren und nachhaltige Ma\u00dfnahmen umzusetzen. Und verstehen Sie, warum Kosten- und Risikomanagement ein unzertrennliches Paar sind.<\/p>\n<p>\ud83c\udfafKOSTEN- UND KOMPLEXIT\u00c4TSMANAGEMENT<br \/>\n\u2714\ufe0fKostenstrukturen und relevante Kostentreiber verstehen und optimieren<br \/>\n\u2714\ufe0fKostenpotentiale identifizieren und umsetzen, Verhandlungen erfolgreich vorbereiten<br \/>\n\u2714\ufe0fZielkosten ermitteln, Total Cost of Ownership Handeln etablieren<br \/>\n\u2714\ufe0fKomplexit\u00e4t reduzieren, B\u00fcndelungs- und Skaleneffekte erzeugen<\/p>\n<p>\ud83c\udfafLIEFERKETTEN &amp; LIEFERANTEN STABILISIEREN, RISIKEN MINIMIEREN<br \/>\n\u2714\ufe0fRisikobewusstsein entwickeln, Verantwortung \u00fcbernehmen<br \/>\n\u2714\ufe0fLieferkettenrisiken erkennen, Signale deuten, Infos validieren<br \/>\n\u2714\ufe0fMarkt- und Lieferkettenrisiken absichern, Pr\u00e4ventions- und Abstellma\u00dfnahmen anwenden<br \/>\n\u2714\ufe0fRisiken im Warengruppen- und Lieferantenmgmt. analysieren, Ergebnisse planbar machen<\/p>\n<p>\ud83d\udc49LERNEN VON KRISENERFAHRENEN PRAKTIKERN<br \/>\nVertrauen Sie Umsetzern, denn herausfordernde Zeiten brauchen Erfahrung und Konzentration auf das Wesentliche, keine Beratung. targetP b\u00fcndelt 80+ Jahre Einkaufs- und F\u00fchrungsexpertise mit 20+ Jahren Erfahrung im Kosten- und Komplexit\u00e4tsmanagement. Wir waren Einkaufsleiter, Risikomanager, Kostenanalytiker und haben Risikomanagement- und Kostenanalyseteams sowie Cost Engineering Organisationen aufgebaut und gef\u00fchrt (u.a. Benteler und AGCO). Unsere vom BME, BVL und dem Forbes Magazin gew\u00fcrdigten Risikomanagement Programme finden in 15 Konzernen und mittelst\u00e4ndischen Unternehmen in Deutschland, USA, Schweden, Hongkong globale Anwendung.<\/p>\n<p>Buchen Sie jetzt zum Vorteilspreis. Mehr Infos auf: kosten-management.de<\/span> <\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"update-components-image        update-components-image--single-image        update-components-mini-update-v2__reshared-content update-components-mini-update-v2__reshared-content--with-divider\"><\/p>\n<div class=\"update-components-image__container-wrapper relative\">\n<div class=\"update-components-image__container            update-components-image__container--preview\"><\/p>\n<div class=\"update-components-image__image-link\">\n<div class=\"ivm-image-view-model\">\n<div class=\"ivm-view-attr__img-wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Insbesondere in Krisenzeiten ist jeder Mitarbeitende im Einkauf gefordert, den wichtigsten Dreiklang des Gesamterfolges zu sichern: \ud83d\udcb0Profitabilit\u00e4t &#8211; Liquidit\u00e4t &#8211; Resilienz \u2753Frage: Kennen Sie die Kostenstrukturen und -risiken Ihrer Lieferanten und wissen Sie um die ergebniswirksamen Werthebel, mit denen Sie das Ergebnis und die Liquidit\u00e4t Ihres Unternehmens st\u00fctzen k\u00f6nnen? Wir bilden Sie daf\u00fcr aus! In unserem praxisnahen Training mit vielen Beispielen und \u00dcbungen erhalten Sie die Werkzeuge und das Wissen, um Kosten und Risiken zu verstehen, Einsparpotentiale zu identifizieren und nachhaltige Ma\u00dfnahmen umzusetzen. Und verstehen Sie, warum Kosten- und Risikomanagement ein unzertrennliches Paar sind. \ud83c\udfafKOSTEN- UND KOMPLEXIT\u00c4TSMANAGEMENT \u2714\ufe0fKostenstrukturen und relevante Kostentreiber verstehen und optimieren \u2714\ufe0fKostenpotentiale identifizieren und umsetzen, Verhandlungen erfolgreich vorbereiten \u2714\ufe0fZielkosten ermitteln, Total Cost of Ownership Handeln etablieren \u2714\ufe0fKomplexit\u00e4t reduzieren, B\u00fcndelungs- und Skaleneffekte erzeugen \ud83c\udfafLIEFERKETTEN &amp; LIEFERANTEN STABILISIEREN, RISIKEN MINIMIEREN \u2714\ufe0fRisikobewusstsein entwickeln, Verantwortung \u00fcbernehmen \u2714\ufe0fLieferkettenrisiken erkennen, Signale deuten, Infos validieren \u2714\ufe0fMarkt- und Lieferkettenrisiken absichern, Pr\u00e4ventions- und Abstellma\u00dfnahmen anwenden \u2714\ufe0fRisiken im Warengruppen- und Lieferantenmgmt. analysieren, Ergebnisse planbar machen \ud83d\udc49LERNEN VON KRISENERFAHRENEN PRAKTIKERN Vertrauen Sie Umsetzern, denn herausfordernde Zeiten brauchen Erfahrung und Konzentration auf das Wesentliche, keine Beratung. targetP b\u00fcndelt 80+ Jahre Einkaufs- und F\u00fchrungsexpertise mit 20+ Jahren Erfahrung im Kosten- und Komplexit\u00e4tsmanagement. Wir waren Einkaufsleiter, Risikomanager, Kostenanalytiker und haben Risikomanagement- und Kostenanalyseteams sowie Cost Engineering Organisationen aufgebaut und gef\u00fchrt (u.a. Benteler und AGCO). Unsere vom BME, BVL und dem Forbes Magazin gew\u00fcrdigten Risikomanagement Programme finden in 15 Konzernen und mittelst\u00e4ndischen Unternehmen in Deutschland, USA, Schweden, Hongkong globale Anwendung. Buchen Sie jetzt zum Vorteilspreis. Mehr Infos auf: kosten-management.de<\/p>","protected":false},"author":2,"featured_media":5033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MENSCHEN ST\u00c4RKEN - KRISEN MEISTERN - targetP<\/title>\n<meta name=\"description\" content=\"Ihr Krisen Training: Kosten senken, risiken minimieren. In Krisenzeiten ist der Einkauf gefordert, den Gesamterfolg zu sichern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interim-manager-einkauf.de\/en\/menschen-staerken-krisen-meistern\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MENSCHEN ST\u00c4RKEN - KRISEN MEISTERN - targetP\" \/>\n<meta property=\"og:description\" content=\"Ihr Krisen Training: Kosten senken, risiken minimieren. In Krisenzeiten ist der Einkauf gefordert, den Gesamterfolg zu sichern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interim-manager-einkauf.de\/en\/menschen-staerken-krisen-meistern\/\" \/>\n<meta property=\"og:site_name\" content=\"targetP\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-25T07:40:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T08:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jan-Henner Thei\u00dfen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jan-Henner Thei\u00dfen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/\"},\"author\":{\"name\":\"Jan-Henner Thei\u00dfen\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/#\/schema\/person\/2a95808f3172240cd87963820c350852\"},\"headline\":\"MENSCHEN ST\u00c4RKEN &#8211; KRISEN MEISTERN\",\"datePublished\":\"2025-02-25T07:40:46+00:00\",\"dateModified\":\"2025-02-25T08:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/#organization\"},\"image\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/\",\"url\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/\",\"name\":\"MENSCHEN ST\u00c4RKEN - KRISEN MEISTERN - targetP\",\"isPartOf\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg\",\"datePublished\":\"2025-02-25T07:40:46+00:00\",\"dateModified\":\"2025-02-25T08:24:31+00:00\",\"description\":\"Ihr Krisen Training: Kosten senken, risiken minimieren. In Krisenzeiten ist der Einkauf gefordert, den Gesamterfolg zu sichern.\",\"breadcrumb\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage\",\"url\":\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg\",\"contentUrl\":\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg\",\"width\":1200,\"height\":657,\"caption\":\"Training Kosten- und Risikomanagement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/interim-manager-einkauf.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MENSCHEN ST\u00c4RKEN &#8211; KRISEN MEISTERN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/#website\",\"url\":\"https:\/\/interim-manager-einkauf.de\/\",\"name\":\"targetP\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/interim-manager-einkauf.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/#organization\",\"name\":\"targetP\",\"url\":\"https:\/\/interim-manager-einkauf.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2024\/05\/logo_targetP_2024_interim_V2.png\",\"contentUrl\":\"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2024\/05\/logo_targetP_2024_interim_V2.png\",\"width\":1280,\"height\":322,\"caption\":\"targetP\"},\"image\":{\"@id\":\"https:\/\/interim-manager-einkauf.de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/#\/schema\/person\/2a95808f3172240cd87963820c350852\",\"name\":\"Jan-Henner Thei\u00dfen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/interim-manager-einkauf.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/91dbbe7329b8b1168ec3929cc7a4771f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/91dbbe7329b8b1168ec3929cc7a4771f?s=96&d=mm&r=g\",\"caption\":\"Jan-Henner Thei\u00dfen\"},\"url\":\"https:\/\/interim-manager-einkauf.de\/en\/author\/jhtheissen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MENSCHEN ST\u00c4RKEN - KRISEN MEISTERN - targetP","description":"Ihr Krisen Training: Kosten senken, risiken minimieren. In Krisenzeiten ist der Einkauf gefordert, den Gesamterfolg zu sichern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interim-manager-einkauf.de\/en\/menschen-staerken-krisen-meistern\/","og_locale":"en_US","og_type":"article","og_title":"MENSCHEN ST\u00c4RKEN - KRISEN MEISTERN - targetP","og_description":"Ihr Krisen Training: Kosten senken, risiken minimieren. In Krisenzeiten ist der Einkauf gefordert, den Gesamterfolg zu sichern.","og_url":"https:\/\/interim-manager-einkauf.de\/en\/menschen-staerken-krisen-meistern\/","og_site_name":"targetP","article_published_time":"2025-02-25T07:40:46+00:00","article_modified_time":"2025-02-25T08:24:31+00:00","og_image":[{"width":1200,"height":657,"url":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg","type":"image\/jpeg"}],"author":"Jan-Henner Thei\u00dfen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jan-Henner Thei\u00dfen","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#article","isPartOf":{"@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/"},"author":{"name":"Jan-Henner Thei\u00dfen","@id":"https:\/\/interim-manager-einkauf.de\/#\/schema\/person\/2a95808f3172240cd87963820c350852"},"headline":"MENSCHEN ST\u00c4RKEN &#8211; KRISEN MEISTERN","datePublished":"2025-02-25T07:40:46+00:00","dateModified":"2025-02-25T08:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/interim-manager-einkauf.de\/#organization"},"image":{"@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage"},"thumbnailUrl":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/","url":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/","name":"MENSCHEN ST\u00c4RKEN - KRISEN MEISTERN - targetP","isPartOf":{"@id":"https:\/\/interim-manager-einkauf.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage"},"image":{"@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage"},"thumbnailUrl":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg","datePublished":"2025-02-25T07:40:46+00:00","dateModified":"2025-02-25T08:24:31+00:00","description":"Ihr Krisen Training: Kosten senken, risiken minimieren. In Krisenzeiten ist der Einkauf gefordert, den Gesamterfolg zu sichern.","breadcrumb":{"@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#primaryimage","url":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg","contentUrl":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2025\/02\/Grafik-Training.jpg","width":1200,"height":657,"caption":"Training Kosten- und Risikomanagement"},{"@type":"BreadcrumbList","@id":"https:\/\/interim-manager-einkauf.de\/menschen-staerken-krisen-meistern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interim-manager-einkauf.de\/"},{"@type":"ListItem","position":2,"name":"MENSCHEN ST\u00c4RKEN &#8211; KRISEN MEISTERN"}]},{"@type":"WebSite","@id":"https:\/\/interim-manager-einkauf.de\/#website","url":"https:\/\/interim-manager-einkauf.de\/","name":"targetP","description":"","publisher":{"@id":"https:\/\/interim-manager-einkauf.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interim-manager-einkauf.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/interim-manager-einkauf.de\/#organization","name":"targetP","url":"https:\/\/interim-manager-einkauf.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interim-manager-einkauf.de\/#\/schema\/logo\/image\/","url":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2024\/05\/logo_targetP_2024_interim_V2.png","contentUrl":"https:\/\/interim-manager-einkauf.de\/wp-content\/uploads\/2024\/05\/logo_targetP_2024_interim_V2.png","width":1280,"height":322,"caption":"targetP"},"image":{"@id":"https:\/\/interim-manager-einkauf.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/interim-manager-einkauf.de\/#\/schema\/person\/2a95808f3172240cd87963820c350852","name":"JAN-HENNER THEISSEN","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interim-manager-einkauf.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/91dbbe7329b8b1168ec3929cc7a4771f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91dbbe7329b8b1168ec3929cc7a4771f?s=96&d=mm&r=g","caption":"Jan-Henner Thei\u00dfen"},"url":"https:\/\/interim-manager-einkauf.de\/en\/author\/jhtheissen\/"}]}},"_links":{"self":[{"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/posts\/5032"}],"collection":[{"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/comments?post=5032"}],"version-history":[{"count":1,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/posts\/5032\/revisions"}],"predecessor-version":[{"id":5034,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/posts\/5032\/revisions\/5034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/media\/5033"}],"wp:attachment":[{"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/media?parent=5032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/categories?post=5032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interim-manager-einkauf.de\/en\/wp-json\/wp\/v2\/tags?post=5032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}